{"id":14550,"date":"2019-05-20T15:12:52","date_gmt":"2019-05-20T15:12:52","guid":{"rendered":"https:\/\/uip.pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/"},"modified":"2020-04-20T15:36:01","modified_gmt":"2020-04-20T15:36:01","slug":"uip-anuncia-novo-projeto-quinta-marques-gomes","status":"publish","type":"post","link":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/","title":{"rendered":"UIP anuncia novo projeto: Quinta Marques Gomes"},"content":{"rendered":"<p>A United Investments Portugal refor\u00e7ou a presen\u00e7a no norte de Portugal, com a aquisi\u00e7\u00e3o da Quinta Marques Gomes, em Vila Nova de Gaia. O novo projeto de luxo prev\u00ea uma forte componente residencial e um empreendimento hoteleiro com <em>destination spa<\/em>. Com um investimento global aproximado de 200 milh\u00f5es de euros, entre cinco e sete anos, este ser\u00e1 um projeto exclusivo e diferenciador do grupo em Portugal.<\/p>\n<p>O novo projeto com o selo da UIP j\u00e1 se encontra em fase de constru\u00e7\u00e3o. Contar\u00e1 com um boutique hotel com uma marca internacional, um spa de refer\u00eancia no panorama nacional e espa\u00e7o de restaura\u00e7\u00e3o, para al\u00e9m de uma forte componente de Real Estate de luxo que combina turismo residencial e unidades de primeira e segunda habita\u00e7\u00e3o \u2013 a venda imobili\u00e1ria j\u00e1 est\u00e1 em curso.<\/p>\n<p><strong>Carlos Leal, diretor geral da United Investments Portugal<\/strong>, afirma: <em>\u201cEste \u00e9 um dos projetos mais ambiciosos do grupo. Estamos muito entusiasmados, uma vez que vem refor\u00e7ar a solidez e crescimento do grupo, bem como a presen\u00e7a da UIP em Portugal, mais concretamente na regi\u00e3o do norte do pa\u00eds, Porto e Vila Nova de Gaia. Ser\u00e1 um projeto diferenciador e com um forte impacto no atual panorama do turismo nacional.\u201d \u00a0<\/em><\/p>\n<p>Com uma localiza\u00e7\u00e3o privilegiada, debru\u00e7ada sobre a foz do Rio Douro e o Oceano Atl\u00e2ntico, rodeada por extensas \u00e1reas verdes, a propriedade conta com uma \u00e1rea de 40 hectares e 115 mil m<sup>2<\/sup> de constru\u00e7\u00e3o.<\/p>\n<p>H\u00e1 mais de 30 anos em Portugal, o novo empreendimento em Vila Nova de Gaia refor\u00e7a a aposta do grupo UIP no mercado nacional onde conta j\u00e1 com projetos no Algarve (Pine Cliffs Resort), Cascais (Sheraton Cascais Resort), Porto (YOTEL Porto) e Lisboa (Hyatt Regency Lisboa).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A United Investments Portugal refor\u00e7ou a presen\u00e7a no norte de Portugal, com a aquisi\u00e7\u00e3o da Quinta Marques Gomes, em Vila Nova de Gaia. O novo projeto de luxo prev\u00ea uma forte componente residencial e um empreendimento hoteleiro com destination spa. Com um investimento global aproximado de 200 milh\u00f5es de euros, entre cinco e sete anos, [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[167,221,168],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UIP anuncia novo projeto: Quinta Marques Gomes - UIP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UIP anuncia novo projeto: Quinta Marques Gomes - UIP\" \/>\n<meta property=\"og:description\" content=\"A United Investments Portugal refor\u00e7ou a presen\u00e7a no norte de Portugal, com a aquisi\u00e7\u00e3o da Quinta Marques Gomes, em Vila Nova de Gaia. O novo projeto de luxo prev\u00ea uma forte componente residencial e um empreendimento hoteleiro com destination spa. Com um investimento global aproximado de 200 milh\u00f5es de euros, entre cinco e sete anos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/\" \/>\n<meta property=\"og:site_name\" content=\"UIP\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-20T15:12:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T15:36:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uip.pt\/wp-content\/uploads\/2020\/09\/UIP-job-offer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Jo\u00e3o Barbedo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uip.pt\/#website\",\"url\":\"https:\/\/uip.pt\/\",\"name\":\"UIP\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uip.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#webpage\",\"url\":\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/\",\"name\":\"UIP anuncia novo projeto: Quinta Marques Gomes - UIP\",\"isPartOf\":{\"@id\":\"https:\/\/uip.pt\/#website\"},\"datePublished\":\"2019-05-20T15:12:52+00:00\",\"dateModified\":\"2020-04-20T15:36:01+00:00\",\"author\":{\"@id\":\"https:\/\/uip.pt\/#\/schema\/person\/6b276f9f6fc1bdcf7d45ce61a96570ff\"},\"breadcrumb\":{\"@id\":\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/uip.pt\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UIP anuncia novo projeto: Quinta Marques Gomes\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/uip.pt\/#\/schema\/person\/6b276f9f6fc1bdcf7d45ce61a96570ff\",\"name\":\"Maria Jo\\u00e3o Barbedo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/uip.pt\/#personlogo\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/459c5f0b549b327d12e0e753b28f6c85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/459c5f0b549b327d12e0e753b28f6c85?s=96&d=mm&r=g\",\"caption\":\"Maria Jo\\u00e3o Barbedo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UIP anuncia novo projeto: Quinta Marques Gomes - UIP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/","og_locale":"pt_PT","og_type":"article","og_title":"UIP anuncia novo projeto: Quinta Marques Gomes - UIP","og_description":"A United Investments Portugal refor\u00e7ou a presen\u00e7a no norte de Portugal, com a aquisi\u00e7\u00e3o da Quinta Marques Gomes, em Vila Nova de Gaia. O novo projeto de luxo prev\u00ea uma forte componente residencial e um empreendimento hoteleiro com destination spa. Com um investimento global aproximado de 200 milh\u00f5es de euros, entre cinco e sete anos, [&hellip;]","og_url":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/","og_site_name":"UIP","article_published_time":"2019-05-20T15:12:52+00:00","article_modified_time":"2020-04-20T15:36:01+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/uip.pt\/wp-content\/uploads\/2020\/09\/UIP-job-offer.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Jo\u00e3o Barbedo","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/uip.pt\/#website","url":"https:\/\/uip.pt\/","name":"UIP","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uip.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#webpage","url":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/","name":"UIP anuncia novo projeto: Quinta Marques Gomes - UIP","isPartOf":{"@id":"https:\/\/uip.pt\/#website"},"datePublished":"2019-05-20T15:12:52+00:00","dateModified":"2020-04-20T15:36:01+00:00","author":{"@id":"https:\/\/uip.pt\/#\/schema\/person\/6b276f9f6fc1bdcf7d45ce61a96570ff"},"breadcrumb":{"@id":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uip.pt\/pt-pt\/uip-anuncia-novo-projeto-quinta-marques-gomes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uip.pt\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"UIP anuncia novo projeto: Quinta Marques Gomes"}]},{"@type":"Person","@id":"https:\/\/uip.pt\/#\/schema\/person\/6b276f9f6fc1bdcf7d45ce61a96570ff","name":"Maria Jo\u00e3o Barbedo","image":{"@type":"ImageObject","@id":"https:\/\/uip.pt\/#personlogo","inLanguage":"pt-PT","url":"https:\/\/secure.gravatar.com\/avatar\/459c5f0b549b327d12e0e753b28f6c85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/459c5f0b549b327d12e0e753b28f6c85?s=96&d=mm&r=g","caption":"Maria Jo\u00e3o Barbedo"}}]}},"_links":{"self":[{"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/14550"}],"collection":[{"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=14550"}],"version-history":[{"count":1,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/14550\/revisions"}],"predecessor-version":[{"id":14551,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/14550\/revisions\/14551"}],"wp:attachment":[{"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=14550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/categories?post=14550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uip.pt\/pt-pt\/wp-json\/wp\/v2\/tags?post=14550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}